{"id":8244,"date":"2018-01-22T17:15:48","date_gmt":"2018-01-22T23:15:48","guid":{"rendered":"https:\/\/www.pearlsonly.com\/blog\/cora-pearl-pendant-white-japanese-akoya-id199565-m-2\/"},"modified":"2018-01-22T17:15:48","modified_gmt":"2018-01-22T23:15:48","slug":"cora-pearl-pendant-white-japanese-akoya-id199565-m-2","status":"inherit","type":"attachment","link":"https:\/\/www.pearlsonly.no\/blog\/cora-pearl-pendant-white-japanese-akoya-id199565-m-2\/","title":{"rendered":"cora-pearl-pendant-white-japanese-akoya-id199565-m"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-8244","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"277\" src=\"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-300x277.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-300x277.jpg 300w, https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-325x300.jpg 325w, https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":350,"height":323,"file":"2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg","sizes":{"thumbnail":{"file":"cora-pearl-pendant-white-japanese-akoya-id199565-m-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-150x150.jpg"},"medium":{"file":"cora-pearl-pendant-white-japanese-akoya-id199565-m-300x277.jpg","width":300,"height":277,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-300x277.jpg"},"post-thumbnail":{"file":"cora-pearl-pendant-white-japanese-akoya-id199565-m-350x288.jpg","width":350,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-350x288.jpg"},"large-feature":{"file":"cora-pearl-pendant-white-japanese-akoya-id199565-m-350x288.jpg","width":350,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-350x288.jpg"},"small-feature":{"file":"cora-pearl-pendant-white-japanese-akoya-id199565-m-325x300.jpg","width":325,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m-325x300.jpg"},"full":{"file":"cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg","width":350,"height":323,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg","filename":"cora-pearl-pendant-white-japanese-akoya-id199565-m.jpg","filesize":7409,"_links":{"self":[{"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/media\/8244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/users\/1"}]}}