{"id":8254,"date":"2018-01-22T17:17:55","date_gmt":"2018-01-22T23:17:55","guid":{"rendered":"https:\/\/www.pearlsonly.com\/blog\/love-pearl-necklace-white-freshwater-id235797-z-3\/"},"modified":"2018-01-22T17:17:55","modified_gmt":"2018-01-22T23:17:55","slug":"love-pearl-necklace-white-freshwater-id235797-z-3","status":"inherit","type":"attachment","link":"https:\/\/www.pearlsonly.no\/blog\/love-pearl-necklace-white-freshwater-id235797-z-3\/","title":{"rendered":"love-pearl-necklace-white-freshwater-id235797-z"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-8254","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"277\" src=\"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-300x277.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-300x277.jpg 300w, https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-768x708.jpg 768w, https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-325x300.jpg 325w, https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":738,"file":"2018\/01\/love-pearl-necklace-white-freshwater-id235797-z.jpg","sizes":{"thumbnail":{"file":"love-pearl-necklace-white-freshwater-id235797-z-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-150x150.jpg"},"medium":{"file":"love-pearl-necklace-white-freshwater-id235797-z-300x277.jpg","width":300,"height":277,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-300x277.jpg"},"medium_large":{"file":"love-pearl-necklace-white-freshwater-id235797-z-768x708.jpg","width":768,"height":708,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-768x708.jpg"},"post-thumbnail":{"file":"love-pearl-necklace-white-freshwater-id235797-z-800x288.jpg","width":800,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-800x288.jpg"},"large-feature":{"file":"love-pearl-necklace-white-freshwater-id235797-z-800x288.jpg","width":800,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-800x288.jpg"},"small-feature":{"file":"love-pearl-necklace-white-freshwater-id235797-z-325x300.jpg","width":325,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z-325x300.jpg"},"full":{"file":"love-pearl-necklace-white-freshwater-id235797-z.jpg","width":800,"height":738,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.pearlsonly.no\/blog\/wp-content\/uploads\/2018\/01\/love-pearl-necklace-white-freshwater-id235797-z.jpg","filename":"love-pearl-necklace-white-freshwater-id235797-z.jpg","filesize":24615,"_links":{"self":[{"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/media\/8254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pearlsonly.no\/blog\/wp-json\/wp\/v2\/users\/1"}]}}